{"id":634,"count":1,"description":"","link":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/","name":"Halloween event","slug":"halloween-event","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Halloween event - Laskmine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halloween event Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/\" \/>\n<meta property=\"og:site_name\" content=\"Laskmine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@combattrainings\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/laskmine.ee\\\/en\\\/tag\\\/halloween-event\\\/\",\"url\":\"https:\\\/\\\/laskmine.ee\\\/en\\\/tag\\\/halloween-event\\\/\",\"name\":\"Halloween event - Laskmine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laskmine.ee\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laskmine.ee\\\/en\\\/tag\\\/halloween-event\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laskmine.ee\\\/en\\\/tag\\\/halloween-event\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laskmine.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halloween event\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laskmine.ee\\\/#website\",\"url\":\"https:\\\/\\\/laskmine.ee\\\/\",\"name\":\"Tondi Lasketiir\",\"description\":\"Tondi Lasketiir\",\"publisher\":{\"@id\":\"https:\\\/\\\/laskmine.ee\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laskmine.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laskmine.ee\\\/#organization\",\"name\":\"Tondi Lasketiir\",\"url\":\"https:\\\/\\\/laskmine.ee\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/laskmine.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laskmine.ee\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ghost-tactics-logo.svg\",\"contentUrl\":\"https:\\\/\\\/laskmine.ee\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/ghost-tactics-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Tondi Lasketiir\"},\"image\":{\"@id\":\"https:\\\/\\\/laskmine.ee\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tondilasketiir\\\/\",\"https:\\\/\\\/x.com\\\/combattrainings\",\"https:\\\/\\\/www.instagram.com\\\/tondi_lasketiir\",\"https:\\\/\\\/www.pinterest.com\\\/TondiLasketiir\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRr8G7eQqIN6E8niQ8HCB7w\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Halloween event - Laskmine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/","og_locale":"en_US","og_type":"article","og_title":"Halloween event Archives","og_url":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/","og_site_name":"Laskmine","twitter_card":"summary_large_image","twitter_site":"@combattrainings","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/","url":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/","name":"Halloween event - Laskmine","isPartOf":{"@id":"https:\/\/laskmine.ee\/#website"},"breadcrumb":{"@id":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/laskmine.ee\/en\/tag\/halloween-event\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/laskmine.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Halloween event"}]},{"@type":"WebSite","@id":"https:\/\/laskmine.ee\/#website","url":"https:\/\/laskmine.ee\/","name":"Tondi Lasketiir","description":"Tondi Lasketiir","publisher":{"@id":"https:\/\/laskmine.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laskmine.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/laskmine.ee\/#organization","name":"Tondi Lasketiir","url":"https:\/\/laskmine.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/laskmine.ee\/#\/schema\/logo\/image\/","url":"https:\/\/laskmine.ee\/wp-content\/uploads\/2019\/09\/ghost-tactics-logo.svg","contentUrl":"https:\/\/laskmine.ee\/wp-content\/uploads\/2019\/09\/ghost-tactics-logo.svg","width":1,"height":1,"caption":"Tondi Lasketiir"},"image":{"@id":"https:\/\/laskmine.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tondilasketiir\/","https:\/\/x.com\/combattrainings","https:\/\/www.instagram.com\/tondi_lasketiir","https:\/\/www.pinterest.com\/TondiLasketiir\/","https:\/\/www.youtube.com\/channel\/UCRr8G7eQqIN6E8niQ8HCB7w"]}]}},"_links":{"self":[{"href":"https:\/\/laskmine.ee\/en\/wp-json\/wp\/v2\/tags\/634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laskmine.ee\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/laskmine.ee\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/laskmine.ee\/en\/wp-json\/wp\/v2\/posts?tags=634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}